{"id":4370,"date":"2023-01-17T12:00:00","date_gmt":"2023-01-17T15:00:00","guid":{"rendered":"https:\/\/perspectivacrista.com\/site\/?post_type=ova_audio&#038;p=4370"},"modified":"2023-01-17T14:42:31","modified_gmt":"2023-01-17T17:42:31","slug":"homens-precisamos-reagir","status":"publish","type":"ova_audio","link":"https:\/\/perspectivacrista.com\/site\/audio\/homens-precisamos-reagir\/","title":{"rendered":"Homens, precisamos reagir"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-4\">\n<div class=\"wp-block-column is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"370\" height=\"400\" src=\"https:\/\/perspectivacrista.com\/site\/wp-content\/uploads\/2022\/06\/370x400host-elienai.png\" alt=\"De modo que para o bem de nossas fam\u00edlias e futuras gera\u00e7\u00f5es, para o bem da igreja de hoje e de amanh\u00e3, e principalmente para a gl\u00f3ria de Cristo, n\u00f3s devemos reagir. Devemos nos levantar e agir como agricultores e soldados, que cultivam e protegem, o jardim que lhes foi confiado.\" class=\"wp-image-4128\" srcset=\"https:\/\/perspectivacrista.com\/site\/wp-content\/uploads\/2022\/06\/370x400host-elienai.png 370w, https:\/\/perspectivacrista.com\/site\/wp-content\/uploads\/2022\/06\/370x400host-elienai-278x300.png 278w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Sugest\u00f5es de Leitura<\/h5>\n\n\n\n<ul>\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/amzn.to\/3WLZk2o\" data-type=\"URL\" data-id=\"https:\/\/amzn.to\/3WLZk2o\" target=\"_blank\">Futuros Homens: Criando meninos para enfrentar gigantes<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/amzn.to\/3Qgr64A\" data-type=\"URL\" data-id=\"https:\/\/amzn.to\/3Qgr64A\" target=\"_blank\" rel=\"noreferrer noopener\">Homens de verdade<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/amzn.to\/3jUk4qj\" data-type=\"URL\" data-id=\"https:\/\/amzn.to\/3jUk4qj\" target=\"_blank\" rel=\"noreferrer noopener\">O homem b\u00edblico: masculinidade, lideran\u00e7a e decis\u00f5es<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/amzn.to\/3ImIOBH\" data-type=\"URL\" data-id=\"https:\/\/amzn.to\/3ImIOBH\" target=\"_blank\" rel=\"noreferrer noopener\">Homens fortes: um guia b\u00e1sico para a lideran\u00e7a familiar<\/a>;<\/li>\n\n\n\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/amzn.to\/3Cnep2g\" data-type=\"URL\" data-id=\"https:\/\/amzn.to\/3Cnep2g\" target=\"_blank\">Homem nota 10: Equipando lideres de car\u00e1ter em casa, na igreja e na comunidade<\/a>.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Ficha T\u00e9cnica<\/h5>\n\n\n\n<ul>\n<li>Texto: <a href=\"https:\/\/perspectivacrista.com\/site\/audio-host\/elienai-b-batista\/\" data-type=\"URL\" data-id=\"https:\/\/perspectivacrista.com\/site\/audio-host\/elienai-b-batista\/\">Pr. Elienai B. Batista<\/a>.<\/li>\n\n\n\n<li>Voz: Pr. Elienai B. Batista.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-container-1\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75 has-custom-font-size is-style-outline has-medium-font-size\"><a class=\"wp-block-button__link has-black-color has-text-color wp-element-button\" href=\"https:\/\/perspectivacrista.com\/site\/quero-apoiar\/\" style=\"border-radius:5px\">Quero Apoiar!<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow\">\n<p>Nos \u00faltimos 20 anos a Reforma no Brasil cresceu consideravelmente em termos de livros, editoras, p\u00e1ginas nas redes sociais, confer\u00eancias, igrejas e pessoas interessadas.<\/p>\n\n\n\n<p>Em certa medida houve avan\u00e7os nas quest\u00f5es doutrin\u00e1rias e lit\u00fargicas. Mas onde est\u00e3o os frutos na vida dos crentes e de suas fam\u00edlias? N\u00e3o avan\u00e7amos muito no que diz respeito \u00e0 pr\u00e1tica \u00e0 qual a nossa f\u00e9 reformada deveria nos conduzir. E isso n\u00e3o \u00e9 um problema na doutrina, mas na sua aplica\u00e7\u00e3o.<\/p>\n\n\n\n<p>N\u00f3s vivemos na era da informa\u00e7\u00e3o, e me parece que \u00e9 exatamente isso que temos valorizado. Nos enchemos de leituras, prega\u00e7\u00f5es, palestras, uma quantidade enorme de informa\u00e7\u00f5es. Mas o que temos feito com tudo isso?<\/p>\n\n\n\n<p>\u00c9 como se tiv\u00e9ssemos uma mesa farta cheia de comidas deliciosas e nutritivas, mas n\u00f3s apenas colocamos na boca para sentir o gosto, mas n\u00e3o mastigamos e digerimos. Apenas provamos e cuspimos.<\/p>\n\n\n\n<p>Por isso, apesar da fartura, ainda vivemos um cristianismo raqu\u00edtico, estagnado, empobrecido quanto aos frutos da verdadeira piedade. Por exemplo, gostamos de ler os puritanos e ouvir a respeito de sua piedade, mas a pergunta \u00e9: queremos viver piedosamente como eles?<\/p>\n\n\n\n<p>Assim como Ad\u00e3o no para\u00edso, n\u00e3o reagiu aos ataques da serpente contra sua esposa, n\u00f3s temos assistido aos ataques do presente sem muita rea\u00e7\u00e3o.<\/p>\n\n\n\n<p>A serpente continua atacando. E uma parte consider\u00e1vel desses ataques \u00e9 contra os homens. O diabo sabe do papel que Deus nos confiou como homens, sabe que assim como Ad\u00e3o, temos a responsabilidade de cultivar e proteger. De maneira que ao nos tornar inoperantes, ele atinge as fam\u00edlias e as igrejas.<\/p>\n\n\n\n<p>Quando ele quis destruir o povo de Deus no Egito, ele procurou destruir os meninos. E hoje ele faz o mesmo. Est\u00e1 destruindo os meninos e rapazes de hoje que s\u00e3o os homens, maridos, pais, pastores, di\u00e1conos e presb\u00edteros de amanh\u00e3.<\/p>\n\n\n\n<p>Nossos meninos e rapazes, em grande parte, est\u00e3o presos \u00e0 uma vida f\u00fatil e infrut\u00edfera. Presos \u00e0 tecnologia, aos jogos e \u00e0 pornografia. Presos \u00e0 ociosidade e \u00e0 ignor\u00e2ncia a respeito da verdadeira piedade.<\/p>\n\n\n\n<p>E a culpa \u00e9 dos homens do presente. Minha culpa. Sua culpa. Como Ad\u00e3o, estamos apenas assistindo a tudo isso. Nossa passividade na fam\u00edlia e na igreja ter\u00e1 consequ\u00eancias sobre nossos filhos, netos, bisnetos e demais gera\u00e7\u00f5es.<\/p>\n\n\n\n<p>De modo que para o bem de nossas fam\u00edlias e futuras gera\u00e7\u00f5es, para o bem da igreja de hoje e de amanh\u00e3, e principalmente para a gl\u00f3ria de Cristo, n\u00f3s devemos reagir. Devemos nos levantar e agir como agricultores e soldados, que cultivam e protegem, o jardim que lhes foi confiado.<\/p>\n\n\n\n<p>Essa rea\u00e7\u00e3o deve come\u00e7ar por aplicarmos \u00e0 nossa pr\u00f3pria vida as preciosas verdades da palavra de Deus \u00e0s quais somos expostos constantemente. Precisamos mastigar e digerir o alimento que nutre a alma.<\/p>\n\n\n\n<p>Assim sendo, o desafio que propomos aos rapazes e homens que n\u00e3o s\u00f3 provem desse conte\u00fado, mas que meditem, orem e apliquem, a fim de que nos tornemos homens fortes e fi\u00e9is no cumprimento da miss\u00e3o que Deus lhes deu.<\/p>\n\n\n\n<p>Encerro encorajando voc\u00ea gastar pelo menos cinco minutos para meditar sobre duas quest\u00f5es:<\/p>\n\n\n\n<ol type=\"1\">\n<li>Sobre sua responsabilidade em rela\u00e7\u00e3o \u00e0 sua fam\u00edlia e \u00e0 sua igreja de hoje e de amanh\u00e3;<\/li>\n\n\n\n<li>Sobre o tipo de homem que voc\u00ea precisa ser em Cristo, para cumprir suas responsabilidades.<\/li>\n<\/ol>\n\n\n\n<p>Medite e ore a respeito.<\/p>\n\n\n\n<p>Que o Senhor te conceda gra\u00e7a e paz!<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>De modo que para o bem de nossas fam\u00edlias e futuras gera\u00e7\u00f5es, para o bem da igreja de hoje e de amanh\u00e3, e principalmente para a gl\u00f3ria de Cristo, n\u00f3s devemos reagir. Devemos nos levantar e agir como agricultores e soldados, que cultivam e protegem, o jardim que lhes foi confiado.<\/p>\n","protected":false},"featured_media":4385,"comment_status":"open","ping_status":"closed","template":"","category_audio":[37],"season_audio":[22],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/perspectivacrista.com\/site\/wp-json\/wp\/v2\/ova_audio\/4370"}],"collection":[{"href":"https:\/\/perspectivacrista.com\/site\/wp-json\/wp\/v2\/ova_audio"}],"about":[{"href":"https:\/\/perspectivacrista.com\/site\/wp-json\/wp\/v2\/types\/ova_audio"}],"replies":[{"embeddable":true,"href":"https:\/\/perspectivacrista.com\/site\/wp-json\/wp\/v2\/comments?post=4370"}],"version-history":[{"count":5,"href":"https:\/\/perspectivacrista.com\/site\/wp-json\/wp\/v2\/ova_audio\/4370\/revisions"}],"predecessor-version":[{"id":4386,"href":"https:\/\/perspectivacrista.com\/site\/wp-json\/wp\/v2\/ova_audio\/4370\/revisions\/4386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perspectivacrista.com\/site\/wp-json\/wp\/v2\/media\/4385"}],"wp:attachment":[{"href":"https:\/\/perspectivacrista.com\/site\/wp-json\/wp\/v2\/media?parent=4370"}],"wp:term":[{"taxonomy":"category_audio","embeddable":true,"href":"https:\/\/perspectivacrista.com\/site\/wp-json\/wp\/v2\/category_audio?post=4370"},{"taxonomy":"season_audio","embeddable":true,"href":"https:\/\/perspectivacrista.com\/site\/wp-json\/wp\/v2\/season_audio?post=4370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}